{"id":8104,"date":"2025-12-03T15:40:59","date_gmt":"2025-12-03T15:40:59","guid":{"rendered":"https:\/\/xtirpa.moodd.online\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/"},"modified":"2025-12-15T17:35:53","modified_gmt":"2025-12-15T17:35:53","slug":"braco-davit-de-48-1200mm-com-adaptadores-fixos","status":"publish","type":"product","link":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/","title":{"rendered":"Bra\u00e7o davit de 48&#8243; | 1200mm com adaptadores fixos"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>Alcance alargado<\/strong><\/p>\n<p style=\"font-weight: 400;\">O IN-8005 \u00e9 um bra\u00e7o davit telesc\u00f3pico robusto com um alcance ajust\u00e1vel de 762 a 1.219 mm.<\/p>\n<p style=\"font-weight: 400;\"><strong>Adaptadores personalizados de acordo com a estrutura<\/strong><\/p>\n<p style=\"font-weight: 400;\">O sistema IN-8005 consiste no mastro IN-2313, no Bra\u00e7o davit IN-2237 e num adaptador fixo de ch\u00e3o ou parede. \u00c9 ideal para entradas verticais em espa\u00e7os confinados onde um adaptador fixo pode ser ancorado ao ch\u00e3o ou \u00e0 parede. O mastro (10,4 kg) e o bra\u00e7o (23 kg) podem ser transportados separadamente.<\/p>\n<p style=\"font-weight: 400;\"><strong>Mastro universal com extens\u00f5es<\/strong><\/p>\n<p style=\"font-weight: 400;\">O mastro e o Bra\u00e7o davit podem rodar 360\u00b0 durante a evacua\u00e7\u00e3o. Quando utiliza um adaptador fixo de ch\u00e3o ou de parede, o mastro pode ser alargado utilizando pe\u00e7as de extens\u00e3o. O SRL pode ser montado mais abaixo para permitir a opera\u00e7\u00e3o da pega de evacua\u00e7\u00e3o, se necess\u00e1rio.<\/p>\n<p style=\"font-weight: 400;\"><strong>Compatibilidade com SRL \/ guincho<\/strong><\/p>\n<p style=\"font-weight: 400;\">O IN-8005 \u00e9 compat\u00edvel com v\u00e1rios guinchos, incluindo o guincho Xtirpa\u2122 IN-2477. Est\u00e3o dispon\u00edveis v\u00e1rios suportes de montagem para uma vasta gama de SRLs com pegas de evacua\u00e7\u00e3o. Utilizando o adaptador SRL\/Winch (A2237-06), pode ser montado um segundo SRL ou guincho no Bra\u00e7o davit. O ponto de ancoragem adicional (A2237-17) oferece op\u00e7\u00f5es adicionais para fixar um guincho de corda ou um guincho de pessoal motorizado.<\/p>\n<p style=\"font-weight: 400;\"><strong>Ponto de ancoragem forte para 3 pessoas<\/strong><\/p>\n<p style=\"font-weight: 400;\">A fixa\u00e7\u00e3o do Bra\u00e7o davit foi concebida para uma carga de trabalho segura at\u00e9 164 kg e uma resist\u00eancia m\u00ednima \u00e0 rutura de 16 kN, o que a torna compat\u00edvel com as normas EN, OSHA, ANSI e CSA. O sistema est\u00e1 certificado para um m\u00e1ximo de tr\u00eas pessoas ao abrigo da norma CEN\/TS 16415. A \u00e2ncora em D de a\u00e7o no centro do bra\u00e7o tem uma resist\u00eancia \u00e0 rutura de 22 kN.<\/p>\n<p style=\"font-weight: 400;\"><strong>Instala\u00e7\u00e3o e movimento r\u00e1pidos e intuitivos<\/strong><\/p>\n<p style=\"font-weight: 400;\">O sistema pode ser instalado em apenas alguns minutos sem ferramentas: o mastro \u00e9 colocado no adaptador e o bra\u00e7o do turco \u00e9 bloqueado no mastro com um pino de seguran\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mastro, bra\u00e7o do turco 1200 mm<\/p>\n","protected":false},"featured_media":6621,"template":"","meta":{"_acf_changed":false},"product_brand":[56],"product_cat":[604],"product_tag":[551],"class_list":{"0":"post-8104","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-xtirpa","7":"product_cat-vertical","8":"product_tag-in-8005","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bra\u00e7o davit de 48&quot; | 1200mm com adaptadores fixos - Xtirpa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bra\u00e7o davit de 48&quot; | 1200mm com adaptadores fixos - Xtirpa\" \/>\n<meta property=\"og:description\" content=\"Mastro, bra\u00e7o do turco 1200 mm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/\" \/>\n<meta property=\"og:site_name\" content=\"Xtirpa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Xtirpa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T17:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/06\/Xtirpa-8005-IN2238-confined-space-1219mm-4822-davit-arm-floor-adapter-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solutions\\\/braco-davit-de-48-1200mm-com-adaptadores-fixos\\\/\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solutions\\\/braco-davit-de-48-1200mm-com-adaptadores-fixos\\\/\",\"name\":\"Bra\u00e7o davit de 48\\\" | 1200mm com adaptadores fixos - Xtirpa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solutions\\\/braco-davit-de-48-1200mm-com-adaptadores-fixos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solutions\\\/braco-davit-de-48-1200mm-com-adaptadores-fixos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Xtirpa-8005-IN2238-confined-space-1219mm-4822-davit-arm-floor-adapter-1.webp\",\"datePublished\":\"2025-12-03T15:40:59+00:00\",\"dateModified\":\"2025-12-15T17:35:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solutions\\\/braco-davit-de-48-1200mm-com-adaptadores-fixos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solutions\\\/braco-davit-de-48-1200mm-com-adaptadores-fixos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solutions\\\/braco-davit-de-48-1200mm-com-adaptadores-fixos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Xtirpa-8005-IN2238-confined-space-1219mm-4822-davit-arm-floor-adapter-1.webp\",\"contentUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Xtirpa-8005-IN2238-confined-space-1219mm-4822-davit-arm-floor-adapter-1.webp\",\"width\":1800,\"height\":1345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solutions\\\/braco-davit-de-48-1200mm-com-adaptadores-fixos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solu\u00e7\u00f5es\",\"item\":\"https:\\\/\\\/xtirpa.moodd.online\\\/pt-pt\\\/solucoes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bra\u00e7o davit de 48&#8243; | 1200mm com adaptadores fixos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#website\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/\",\"name\":\"Xtirpa\u2122 - Confined Space and work at height Safety Solutions\",\"description\":\"Engineered safety for access and rescue\",\"publisher\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#organization\"},\"alternateName\":\"Xtirpa\u2122 safety for access and rescue at height and confined space\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xtirpa.moodd.online\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#organization\",\"name\":\"Xtirpa\u2122 - PSP Innova Inc.\",\"alternateName\":\"PSP Innova Inc. - Xtirpa\u2122\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/XTIRPA_yellow.png\",\"contentUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/XTIRPA_yellow.png\",\"width\":1571,\"height\":544,\"caption\":\"Xtirpa\u2122 - PSP Innova Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Xtirpa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/psp-innova\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@xtirpa\",\"https:\\\/\\\/www.instagram.com\\\/xtirpa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bra\u00e7o davit de 48\" | 1200mm com adaptadores fixos - Xtirpa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/","og_locale":"pt_PT","og_type":"article","og_title":"Bra\u00e7o davit de 48\" | 1200mm com adaptadores fixos - Xtirpa","og_description":"Mastro, bra\u00e7o do turco 1200 mm","og_url":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/","og_site_name":"Xtirpa","article_publisher":"https:\/\/www.facebook.com\/Xtirpa\/","article_modified_time":"2025-12-15T17:35:53+00:00","og_image":[{"width":1800,"height":1345,"url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/06\/Xtirpa-8005-IN2238-confined-space-1219mm-4822-davit-arm-floor-adapter-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/","url":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/","name":"Bra\u00e7o davit de 48\" | 1200mm com adaptadores fixos - Xtirpa","isPartOf":{"@id":"https:\/\/xtirpa.moodd.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/#primaryimage"},"image":{"@id":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/#primaryimage"},"thumbnailUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/06\/Xtirpa-8005-IN2238-confined-space-1219mm-4822-davit-arm-floor-adapter-1.webp","datePublished":"2025-12-03T15:40:59+00:00","dateModified":"2025-12-15T17:35:53+00:00","breadcrumb":{"@id":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/#primaryimage","url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/06\/Xtirpa-8005-IN2238-confined-space-1219mm-4822-davit-arm-floor-adapter-1.webp","contentUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/06\/Xtirpa-8005-IN2238-confined-space-1219mm-4822-davit-arm-floor-adapter-1.webp","width":1800,"height":1345},{"@type":"BreadcrumbList","@id":"https:\/\/xtirpa.moodd.online\/pt-pt\/solutions\/braco-davit-de-48-1200mm-com-adaptadores-fixos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xtirpa.moodd.online\/pt-pt\/casa\/"},{"@type":"ListItem","position":2,"name":"Solu\u00e7\u00f5es","item":"https:\/\/xtirpa.moodd.online\/pt-pt\/solucoes\/"},{"@type":"ListItem","position":3,"name":"Bra\u00e7o davit de 48&#8243; | 1200mm com adaptadores fixos"}]},{"@type":"WebSite","@id":"https:\/\/xtirpa.moodd.online\/#website","url":"https:\/\/xtirpa.moodd.online\/","name":"Xtirpa\u2122 - Confined Space and work at height Safety Solutions","description":"Engineered safety for access and rescue","publisher":{"@id":"https:\/\/xtirpa.moodd.online\/#organization"},"alternateName":"Xtirpa\u2122 safety for access and rescue at height and confined space","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xtirpa.moodd.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/xtirpa.moodd.online\/#organization","name":"Xtirpa\u2122 - PSP Innova Inc.","alternateName":"PSP Innova Inc. - Xtirpa\u2122","url":"https:\/\/xtirpa.moodd.online\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/xtirpa.moodd.online\/#\/schema\/logo\/image\/","url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/03\/XTIRPA_yellow.png","contentUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/03\/XTIRPA_yellow.png","width":1571,"height":544,"caption":"Xtirpa\u2122 - PSP Innova Inc."},"image":{"@id":"https:\/\/xtirpa.moodd.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Xtirpa\/","https:\/\/www.linkedin.com\/company\/psp-innova\/","https:\/\/www.youtube.com\/@xtirpa","https:\/\/www.instagram.com\/xtirpa\/"]}]}},"_links":{"self":[{"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/product\/8104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/product\/8104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/media\/6621"}],"wp:attachment":[{"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/media?parent=8104"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=8104"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=8104"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xtirpa.moodd.online\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=8104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}