{"id":5709,"date":"2025-10-25T16:10:31","date_gmt":"2025-10-25T21:10:31","guid":{"rendered":"https:\/\/xtirpa.moodd.online\/azienda\/"},"modified":"2026-01-14T04:32:26","modified_gmt":"2026-01-14T09:32:26","slug":"azienda","status":"publish","type":"page","link":"https:\/\/xtirpa.moodd.online\/it\/azienda\/","title":{"rendered":"Azienda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5709\" class=\"elementor elementor-5709 elementor-4079\" data-elementor-post-type=\"page\">\n\t\t\t\t<section data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/download-3-1.jpg\" class=\"elementor-element elementor-element-f6b17e6 e-con-full e-flex e-con e-parent\" data-id=\"f6b17e6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf8540 elementor-widget elementor-widget-breadcrumbs\" data-id=\"7bf8540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t\t<div id=\"breadcrumbs\"><span><span><a href=\"https:\/\/xtirpa.moodd.online\/it\/home\/\">Home<\/a><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6aca4a7 elementor-widget elementor-widget-heading\" data-id=\"6aca4a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PSP Innova - Xtirpa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00a4126 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"00a4126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ci impegniamo a progettare e disegnare i sistemi di protezione anticaduta e di salvataggio\/recupero pi\u00f9 innovativi del mercato.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-19db187 e-con-full e-flex e-con e-parent\" data-id=\"19db187\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1d5b3ec e-con-full e-flex e-con e-child\" data-id=\"1d5b3ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d7c084 elementor-widget elementor-widget-heading\" data-id=\"9d7c084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La nostra missione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b662c5e elementor-widget elementor-widget-heading\" data-id=\"b662c5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Innova rivoluziona la progettazione delle attrezzature di salvataggio e recupero in spazi confinati per creare ambienti di lavoro pi\u00f9 sicuri<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2274942 elementor-widget elementor-widget-text-editor\" data-id=\"2274942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ci impegniamo a progettare e disegnare i sistemi di protezione anticaduta e di salvataggio\/recupero pi\u00f9 innovativi del mercato. La nostra missione principale \u00e8 quella di reinventare l&#8217;approccio al lavoro in spazi confinati. Forniamo soluzioni e sistemi di alta qualit\u00e0 e all&#8217;avanguardia che offrono alle industrie gli strumenti per ridurre al minimo gli infortuni e mantenere un ambiente sicuro per le squadre che lavorano in spazi confinati.  <\/p><p>Per molti anni, le industrie hanno compromesso la sicurezza dei dipendenti perch\u00e9 la maggior parte dei sistemi di salvataggio e recupero non erano stati progettati per adattarsi a spazi di lavoro confinati non convenzionali.<\/p><p>INNOVA, con il suo personale esperto e dedicato, progetta soluzioni ergonomiche per creare l&#8217;ambiente di lavoro pi\u00f9 sicuro possibile per lo svolgimento di attivit\u00e0 in spazi ristretti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0b8e9b e-con-full e-flex e-con e-child\" data-id=\"a0b8e9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f244bf8 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"f244bf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download.jpg\" class=\"attachment-full size-full wp-image-5714\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca4463f e-con-full e-flex e-con e-parent\" data-id=\"ca4463f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3a38238 e-con-full e-flex e-con e-child\" data-id=\"3a38238\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5a59ca elementor-widget elementor-widget-heading\" data-id=\"a5a59ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La nostra storia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-803e6e3 elementor-widget elementor-widget-heading\" data-id=\"803e6e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'inizio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4148c60 elementor-widget elementor-widget-heading\" data-id=\"4148c60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1998<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2684bdf dce_masking-none elementor-widget elementor-widget-image\" data-id=\"2684bdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1800\" height=\"1200\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/xtirpa-academy-confined-space-access-rescue-7033.webp\" class=\"attachment-full size-full wp-image-9363\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/xtirpa-academy-confined-space-access-rescue-7033.webp 1800w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/xtirpa-academy-confined-space-access-rescue-7033-300x200.webp 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/xtirpa-academy-confined-space-access-rescue-7033-1024x683.webp 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/xtirpa-academy-confined-space-access-rescue-7033-768x512.webp 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/xtirpa-academy-confined-space-access-rescue-7033-1536x1024.webp 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/xtirpa-academy-confined-space-access-rescue-7033-600x400.webp 600w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a55483e e-con-full e-flex e-con e-child\" data-id=\"a55483e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d36d49e elementor-widget elementor-widget-text-editor\" data-id=\"d36d49e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nel 1998, Martin Dufour e Denis Poissant, due amici con esperienza nelle vendite e nella distribuzione nel settore dei servizi di pubblica utilit\u00e0, hanno creato la loro nicchia di mercato nella distribuzione di attrezzature industriali a importanti aziende come Hydro-Qu\u00e9bec e Bell Canada. Grazie alla distribuzione di attrezzature di alta qualit\u00e0 e a un ottimo servizio clienti, INNOVA si \u00e8 guadagnata un&#8217;ottima reputazione nel settore dei servizi pubblici della provincia del Quebec. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a9a9b8 e-con-full e-flex e-con e-parent\" data-id=\"9a9a9b8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-70281c0 e-con-full e-flex e-con e-child\" data-id=\"70281c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc95c49 elementor-widget elementor-widget-text-editor\" data-id=\"cc95c49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nel 2000 INNOVA ha individuato e colto l&#8217;opportunit\u00e0 di soddisfare un&#8217;esigenza del mercato. Si trattava di fornire attrezzature specializzate per il salvataggio\/recupero di spazi confinati a industrie che non avevano soluzioni. Dopo due anni di ricerche, Innova ha ottenuto un contratto con Hydro-Quebec per 287 sistemi di barricate per tombini. Ad oggi, il sistema di transenna per pozzetti Xtirpa \u00e8 il nostro prodotto di punta e il pi\u00f9 venduto.     <\/p><p>La decisione di dedicarsi al settore degli spazi confinati \u00e8 stata presa. INNOVA ha investito molto in ingegneria, design, lavoratori qualificati e attrezzature di produzione di qualit\u00e0 superiore. Oggi, grazie alla determinazione e all&#8217;impegno del team INNOVA, offriamo le attrezzature per spazi confinati pi\u00f9 leggere, resistenti, innovative e modulari del mercato.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c4a1ee1 e-con-full e-flex e-con e-child\" data-id=\"c4a1ee1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9d13cc elementor-widget elementor-widget-heading\" data-id=\"b9d13cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il duro lavoro incontra l'opportunit\u00e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a01651 elementor-widget elementor-widget-heading\" data-id=\"2a01651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2000<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf746f dce_masking-none elementor-widget elementor-widget-image\" data-id=\"ecf746f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/DJI_0816-scaled-1.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c0bb7d e-con-full e-flex e-con e-parent\" data-id=\"9c0bb7d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0b710a3 e-con-full e-flex e-con e-child\" data-id=\"0b710a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec49bdb dce_masking-none elementor-widget elementor-widget-image\" data-id=\"ec49bdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1.jpg\" class=\"attachment-full size-full wp-image-5715\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-1-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a37845b e-con-full e-flex e-con e-child\" data-id=\"a37845b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c6f964 elementor-widget elementor-widget-heading\" data-id=\"1c6f964\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INGEGNERIA E DESIGN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee64ca1 elementor-widget elementor-widget-text-editor\" data-id=\"ee64ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>INNOVA continua a investire in nuove tecnologie di progettazione, macchinari CNC, saldatura robotizzata e attrezzature di prova per poter offrire le attrezzature pi\u00f9 avanzate al settore degli spazi confinati.<\/p><p>Gli investimenti pi\u00f9 importanti che facciamo sono nel nostro team. La dedizione e l&#8217;energia dei nostri progettisti, ingegneri, saldatori, macchinisti e di tutti gli altri membri del nostro team sono il cuore e l&#8217;anima di Innova. La loro visione comune di fornire alle persone che si occupano quotidianamente dell&#8217;ingresso in spazi confinati le attrezzature pi\u00f9 leggere, resistenti e durevoli del mercato \u00e8 ci\u00f2 che ci rende leader mondiali e invidiati dal settore.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-background-color=\"#F4BE30\" class=\"elementor-element elementor-element-3353e09 elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"3353e09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">scopri le nostre soluzioni<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<section data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/download-3.jpg\" class=\"elementor-element elementor-element-b4a718c e-flex e-con-boxed e-con e-parent\" data-id=\"b4a718c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_range&quot;:&quot;viewport&quot;,&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-dce-background-color=\"#000000\" class=\"elementor-element elementor-element-6e3e7c5 e-con-full e-flex e-con e-child\" data-id=\"6e3e7c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3caae5 elementor-widget elementor-widget-heading\" data-id=\"f3caae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il nostro impegno per la sicurezza<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e88ee0e elementor-widget elementor-widget-text-editor\" data-id=\"e88ee0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Innova offre al settore della sicurezza i sistemi pi\u00f9 innovativi e di alta qualit\u00e0 presenti sul mercato.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0be8ca6 elementor-widget elementor-widget-text-editor\" data-id=\"0be8ca6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Innova, con la sua linea di attrezzature per la protezione anticaduta e il salvataggio\/recupero in spazi confinati XTIRPA\u2122, soddisfa i requisiti di protezione anticaduta pi\u00f9 esigenti al mondo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5712cc9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5712cc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">scopri i nostri partner<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PSP Innova &#8211; Xtirpa Ci impegniamo a progettare e disegnare i sistemi di protezione anticaduta e di salvataggio\/recupero pi\u00f9 innovativi del mercato. La nostra missione Innova rivoluziona la progettazione delle attrezzature di salvataggio e recupero in spazi confinati per creare ambienti di lavoro pi\u00f9 sicuri Ci impegniamo a progettare e disegnare i sistemi di protezione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5709","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La storia di Xtirpa di PSP Innova Inc. il viaggio nella sicurezza -% Xtirpa%<\/title>\n<meta name=\"description\" content=\"Esplora la storia di Xtirpa di PSP Innova Inc. e scopri le innovazioni nei sistemi di protezione e salvataggio dalle cadute.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xtirpa.moodd.online\/it\/azienda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La storia di Xtirpa di PSP Innova Inc. il viaggio nella sicurezza -% Xtirpa%\" \/>\n<meta property=\"og:description\" content=\"Esplora la storia di Xtirpa di PSP Innova Inc. e scopri le innovazioni nei sistemi di protezione e salvataggio dalle cadute.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xtirpa.moodd.online\/it\/azienda\/\" \/>\n<meta property=\"og:site_name\" content=\"Xtirpa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Xtirpa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T09:32:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/azienda\\\/\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/azienda\\\/\",\"name\":\"La storia di Xtirpa di PSP Innova Inc. il viaggio nella sicurezza -% Xtirpa%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/azienda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/azienda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/download.jpg\",\"datePublished\":\"2025-10-25T21:10:31+00:00\",\"dateModified\":\"2026-01-14T09:32:26+00:00\",\"description\":\"Esplora la storia di Xtirpa di PSP Innova Inc. e scopri le innovazioni nei sistemi di protezione e salvataggio dalle cadute.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/azienda\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/azienda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/azienda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/download.jpg\",\"contentUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/download.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/azienda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xtirpa.moodd.online\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azienda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#website\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/\",\"name\":\"Xtirpa\u2122 - Confined Space and work at height Safety Solutions\",\"description\":\"Engineered safety for access and rescue\",\"publisher\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#organization\"},\"alternateName\":\"Xtirpa\u2122 safety for access and rescue at height and confined space\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xtirpa.moodd.online\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#organization\",\"name\":\"Xtirpa\u2122 - PSP Innova Inc.\",\"alternateName\":\"PSP Innova Inc. - Xtirpa\u2122\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/XTIRPA_yellow.png\",\"contentUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/XTIRPA_yellow.png\",\"width\":1571,\"height\":544,\"caption\":\"Xtirpa\u2122 - PSP Innova Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Xtirpa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/psp-innova\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@xtirpa\",\"https:\\\/\\\/www.instagram.com\\\/xtirpa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La storia di Xtirpa di PSP Innova Inc. il viaggio nella sicurezza -% Xtirpa%","description":"Esplora la storia di Xtirpa di PSP Innova Inc. e scopri le innovazioni nei sistemi di protezione e salvataggio dalle cadute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xtirpa.moodd.online\/it\/azienda\/","og_locale":"it_IT","og_type":"article","og_title":"La storia di Xtirpa di PSP Innova Inc. il viaggio nella sicurezza -% Xtirpa%","og_description":"Esplora la storia di Xtirpa di PSP Innova Inc. e scopri le innovazioni nei sistemi di protezione e salvataggio dalle cadute.","og_url":"https:\/\/xtirpa.moodd.online\/it\/azienda\/","og_site_name":"Xtirpa","article_publisher":"https:\/\/www.facebook.com\/Xtirpa\/","article_modified_time":"2026-01-14T09:32:26+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xtirpa.moodd.online\/it\/azienda\/","url":"https:\/\/xtirpa.moodd.online\/it\/azienda\/","name":"La storia di Xtirpa di PSP Innova Inc. il viaggio nella sicurezza -% Xtirpa%","isPartOf":{"@id":"https:\/\/xtirpa.moodd.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xtirpa.moodd.online\/it\/azienda\/#primaryimage"},"image":{"@id":"https:\/\/xtirpa.moodd.online\/it\/azienda\/#primaryimage"},"thumbnailUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download.jpg","datePublished":"2025-10-25T21:10:31+00:00","dateModified":"2026-01-14T09:32:26+00:00","description":"Esplora la storia di Xtirpa di PSP Innova Inc. e scopri le innovazioni nei sistemi di protezione e salvataggio dalle cadute.","breadcrumb":{"@id":"https:\/\/xtirpa.moodd.online\/it\/azienda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xtirpa.moodd.online\/it\/azienda\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/xtirpa.moodd.online\/it\/azienda\/#primaryimage","url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download.jpg","contentUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/xtirpa.moodd.online\/it\/azienda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xtirpa.moodd.online\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Azienda"}]},{"@type":"WebSite","@id":"https:\/\/xtirpa.moodd.online\/#website","url":"https:\/\/xtirpa.moodd.online\/","name":"Xtirpa\u2122 - Confined Space and work at height Safety Solutions","description":"Engineered safety for access and rescue","publisher":{"@id":"https:\/\/xtirpa.moodd.online\/#organization"},"alternateName":"Xtirpa\u2122 safety for access and rescue at height and confined space","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xtirpa.moodd.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/xtirpa.moodd.online\/#organization","name":"Xtirpa\u2122 - PSP Innova Inc.","alternateName":"PSP Innova Inc. - Xtirpa\u2122","url":"https:\/\/xtirpa.moodd.online\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/xtirpa.moodd.online\/#\/schema\/logo\/image\/","url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/03\/XTIRPA_yellow.png","contentUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/03\/XTIRPA_yellow.png","width":1571,"height":544,"caption":"Xtirpa\u2122 - PSP Innova Inc."},"image":{"@id":"https:\/\/xtirpa.moodd.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Xtirpa\/","https:\/\/www.linkedin.com\/company\/psp-innova\/","https:\/\/www.youtube.com\/@xtirpa","https:\/\/www.instagram.com\/xtirpa\/"]}]}},"_links":{"self":[{"href":"https:\/\/xtirpa.moodd.online\/it\/wp-json\/wp\/v2\/pages\/5709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xtirpa.moodd.online\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xtirpa.moodd.online\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xtirpa.moodd.online\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xtirpa.moodd.online\/it\/wp-json\/wp\/v2\/comments?post=5709"}],"version-history":[{"count":2,"href":"https:\/\/xtirpa.moodd.online\/it\/wp-json\/wp\/v2\/pages\/5709\/revisions"}],"predecessor-version":[{"id":9365,"href":"https:\/\/xtirpa.moodd.online\/it\/wp-json\/wp\/v2\/pages\/5709\/revisions\/9365"}],"wp:attachment":[{"href":"https:\/\/xtirpa.moodd.online\/it\/wp-json\/wp\/v2\/media?parent=5709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}