{"id":5701,"date":"2025-10-26T13:57:01","date_gmt":"2025-10-26T18:57:01","guid":{"rendered":"https:\/\/xtirpa.moodd.online\/services\/"},"modified":"2025-12-20T12:55:34","modified_gmt":"2025-12-20T17:55:34","slug":"services","status":"publish","type":"page","link":"https:\/\/xtirpa.moodd.online\/fr\/services\/","title":{"rendered":"Services"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5701\" class=\"elementor elementor-5701 elementor-4393\" data-elementor-post-type=\"page\">\n\t\t\t\t<section data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/xtripa-systems-copy-scaled.webp\" class=\"elementor-element elementor-element-f6b17e6 e-con-full e-flex e-con e-parent\" data-id=\"f6b17e6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2eec02e elementor-widget elementor-widget-dce-breadcrumbs\" data-id=\"2eec02e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dce-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div><span><span><a href=\"https:\/\/xtirpa.moodd.online\/fr\/accueil\/\">Home<\/a><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6aca4a7 elementor-widget elementor-widget-heading\" data-id=\"6aca4a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">UNE GAMME COMPL\u00c8TE DE SERVICES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00a4126 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"00a4126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre \u00e9quipe d'experts a acquis une expertise internationale dans le d\u00e9veloppement de solutions pour les espaces confin\u00e9s.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c2fad07 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"c2fad07\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:60,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-21c57e9 e-grid e-con-full e-con e-child\" data-id=\"21c57e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0a1f9e elementor-align-left elementor-widget elementor-widget-button\" data-id=\"a0a1f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#Consulting\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-pencilcondor\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conseil<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c1fdad elementor-align-left elementor-widget elementor-widget-button\" data-id=\"0c1fdad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#Installation\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-attach\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Installation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c34d098 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c34d098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#CostumSolutions\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-assetscondor\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solutions Costum<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca8e732 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"ca8e732\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#Training\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-people-arrows\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Formation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75ab63e elementor-align-left elementor-widget elementor-widget-button\" data-id=\"75ab63e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#TestLab\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-gitlab\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Laboratoire d'essai<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a2bec elementor-align-left elementor-widget elementor-widget-button\" data-id=\"29a2bec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#Consulting\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-project-diagram\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tra\u00e7abilit\u00e9 des produits<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/mesh-gradient-01.webp\" class=\"elementor-element elementor-element-19db187 e-con-full e-flex e-con e-parent\" data-id=\"19db187\" data-element_type=\"container\" data-e-type=\"container\" id=\"Consulting\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1d5b3ec e-con-full e-flex e-con e-child\" data-id=\"1d5b3ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d7c084 elementor-widget elementor-widget-heading\" data-id=\"9d7c084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Consultation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2274942 elementor-widget elementor-widget-text-editor\" data-id=\"2274942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Au fil des ans, <strong>INNOVA a acquis une expertise internationale dans le d\u00e9veloppement de solutions pour les espaces confin\u00e9s<\/strong>, avec une grande vari\u00e9t\u00e9 de produits de protection contre les chutes et de sauvetage les plus innovants.<\/p><p>Nous sommes convaincus que nous pouvons aider et fournir des solutions pour mieux servir et accompagner les responsables de la s\u00e9curit\u00e9, tout en r\u00e9pondant \u00e0 leurs besoins et \u00e0 leurs attentes en mati\u00e8re de cr\u00e9ation d&rsquo;un environnement de travail s\u00fbr.<\/p><p>INNOVA s&rsquo;engage \u00e0 vous offrir <strong>les solutions les meilleures et les plus innovantes du march\u00e9<\/strong>, afin de r\u00e9pondre aux r\u00e9glementations sp\u00e9cifiques en mati\u00e8re d&rsquo;espaces confin\u00e9s et de s\u00e9curit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7718e20 elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"7718e20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"http:\/\/xtirpa.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez notre \u00e9quipe d'experts<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0b8e9b e-con-full e-flex e-con e-child\" data-id=\"a0b8e9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f244bf8 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"f244bf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg\" class=\"attachment-full size-full wp-image-4441\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0341df1 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"0341df1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1.jpg\" class=\"attachment-full size-full wp-image-4440\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/mesh-gradient-02.webp\" class=\"elementor-element elementor-element-1938a62 e-con-full e-flex e-con e-parent\" data-id=\"1938a62\" data-element_type=\"container\" data-e-type=\"container\" id=\"Installation\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-53f37c7 e-con-full e-flex e-con e-child\" data-id=\"53f37c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e71a416 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"e71a416\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3.jpg\" class=\"attachment-full size-full wp-image-4136\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-3-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e86f931 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"e86f931\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/07\/download-2.jpg\" class=\"attachment-full size-full wp-image-3432\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/07\/download-2.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/07\/download-2-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/07\/download-2-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/07\/download-2-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/07\/download-2-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/07\/download-2-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/07\/download-2-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-548bf8a e-con-full e-flex e-con e-child\" data-id=\"548bf8a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60ac325 elementor-widget elementor-widget-heading\" data-id=\"60ac325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. L'installation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6abe14b elementor-widget elementor-widget-text-editor\" data-id=\"6abe14b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>INNOVA, l&rsquo;un des<strong>fabricants les plus innovants de produits de protection contre les chutes et de sauvetage<\/strong>, s&rsquo;est red\u00e9fini afin de fournir \u00e0 ses clients des solutions compl\u00e8tes cl\u00e9s en main.<\/p><p><strong>Des ann\u00e9es d&rsquo;exp\u00e9rience dans l&rsquo;installation de syst\u00e8mes XTIRPA\u2122<\/strong> nous ont permis d&rsquo;acqu\u00e9rir les connaissances n\u00e9cessaires pour \u00e9duquer et former nos partenaires dans le monde entier.<\/p><p>INNOVA utilise un \u00e9quipement de pointe pour r\u00e9aliser des <strong>installations certifi\u00e9es<\/strong>, positionnant la gamme de produits XTIRPA\u2122 dans une classe sup\u00e9rieure de <strong>services de haute qualit\u00e9<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01af921 elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"01af921\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"http:\/\/xtirpa.com\/company\/partners\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">d\u00e9couvrez nos partenaires<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/mesh-gradient-03.webp\" class=\"elementor-element elementor-element-6cbe442 e-con-full e-flex e-con e-parent\" data-id=\"6cbe442\" data-element_type=\"container\" data-e-type=\"container\" id=\"CustomSolutions\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-662823b e-con-full e-flex e-con e-child\" data-id=\"662823b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4945828 elementor-widget elementor-widget-heading\" data-id=\"4945828\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Solutions personnalis\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2248ba1 elementor-widget elementor-widget-text-editor\" data-id=\"2248ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>INNOVA offre une gamme de<strong> syst\u00e8mes qui peuvent \u00eatre adapt\u00e9s<\/strong> pour permettre \u00e0 n&rsquo;importe quel travailleur d&rsquo;<strong> effectuer ses t\u00e2ches quotidiennes en toute s\u00e9curit\u00e9.<\/strong><\/p><p>L&rsquo;investissement dans des technologies et des mat\u00e9riaux de pointe permet \u00e0 INNOVA de concevoir et d&rsquo;\u00e9laborer des <strong>produits sur mesure adapt\u00e9s \u00e0 tout espace confin\u00e9 non conventionnel<\/strong>.<\/p><p>La distance n&rsquo;est plus une excuse pour ne pas faire appel \u00e0 nos services d&rsquo;ing\u00e9nierie et de conception sp\u00e9cialis\u00e9s.<\/p><p>Nous pouvons fournir des solutions techniques pour tout espace confin\u00e9 sp\u00e9cifique. INNOVA s&rsquo;engage \u00e0 vous offrir les produits les meilleurs et les plus innovants du march\u00e9. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5976326 elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"5976326\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"http:\/\/xtirpa.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">demande de devis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abee7da e-con-full e-flex e-con e-child\" data-id=\"abee7da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f3766d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"9f3766d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-5.jpg\" class=\"attachment-full size-full wp-image-4463\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-5.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-5-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-5-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-5-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-5-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-5-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-5-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/mesh-gradient-04.webp\" class=\"elementor-element elementor-element-abba868 e-con-full e-flex e-con e-parent\" data-id=\"abba868\" data-element_type=\"container\" data-e-type=\"container\" id=\"Training\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-46865bc e-con-full e-flex e-con e-child\" data-id=\"46865bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-053d37d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"053d37d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-17.jpg\" class=\"attachment-full size-full wp-image-4282\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e286bfc dce_masking-none elementor-widget elementor-widget-image\" data-id=\"e286bfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-15.jpg\" class=\"attachment-full size-full wp-image-4097\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-15.jpg 600w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-15-300x300.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-15-150x150.jpg 150w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-15-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-450de40 e-con-full e-flex e-con e-child\" data-id=\"450de40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8fcc4f9 elementor-widget elementor-widget-heading\" data-id=\"8fcc4f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. La formation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a803e6c elementor-widget elementor-widget-text-editor\" data-id=\"a803e6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Au fil des ann\u00e9es, nous avons acquis une expertise sp\u00e9cifique dans le domaine des espaces confin\u00e9s en traitant de nombreux secteurs d&rsquo;intervention diff\u00e9rents et sp\u00e9cifiques.<\/p><p>Toutes ces connaissances sont d\u00e9sormais mises \u00e0 la disposition de tous nos partenaires et clients au sein de l&rsquo;Acad\u00e9mie Xtirpa\u2122.<\/p><p>Nous avons cr\u00e9\u00e9 un <strong>espace o\u00f9 vous pouvez d\u00e9couvrir notre gamme de produits et apprendre les proc\u00e9dures d&rsquo;acc\u00e8s et de sauvetage<\/strong> li\u00e9es aux diff\u00e9rents types d&rsquo;espaces confin\u00e9s.<\/p><p>Des syst\u00e8mes d&rsquo;acc\u00e8s et de sauvetage horizontaux, verticaux et inclin\u00e9s sont disponibles. Pour chacune de ces situations particuli\u00e8res, nous proposons des <strong>cours de formation sp\u00e9cifiques et des sessions en direct con\u00e7ues pour acqu\u00e9rir toutes les connaissances n\u00e9cessaires pour travailler dans ces espaces confin\u00e9s<\/strong>. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db8037f elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"db8037f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"http:\/\/xtirpa.com\/academy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">d\u00e9couvrez notre acad\u00e9mie<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/mesh-gradient-02.webp\" class=\"elementor-element elementor-element-3cea6ab e-con-full e-flex e-con e-parent\" data-id=\"3cea6ab\" data-element_type=\"container\" data-e-type=\"container\" id=\"TestLab\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ee38077 e-con-full e-flex e-con e-child\" data-id=\"ee38077\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d381b1 elementor-widget elementor-widget-heading\" data-id=\"1d381b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Laboratoire d'essai<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29a104 elementor-widget elementor-widget-text-editor\" data-id=\"d29a104\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1a7a68 elementor-widget elementor-widget-heading\" data-id=\"a1a7a68\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><h5 class=\"elementor-heading-title elementor-size-default\">Centre d&rsquo;essais \u00e0 la pointe de la technologie<\/h5><\/div><\/div><p>INNOVA est fi\u00e8re de concevoir et de fabriquer les <strong>produits<\/strong> les plus polyvalents et les plus <strong>ergonomiques dans le domaine de la s\u00e9curit\u00e9<\/strong>.<\/p><p>C&rsquo;est pourquoi nous avons d\u00e9velopp\u00e9 un <strong>laboratoire d&rsquo;essai qui nous permet d&rsquo;am\u00e9liorer et d&rsquo;optimiser nos concepts.<\/strong> Le laboratoire utilise des poids et des capteurs contr\u00f4l\u00e9s qui sont continuellement calibr\u00e9s selon nos normes de qualit\u00e9 <em><strong>ISO-17025 QC<\/strong><\/em> ISO-17025. <\/p><p>Cela nous permet de <strong>tester les<\/strong> comportements <strong>statiques, dynamiques<\/strong> et de stabilit\u00e9 de nos produits afin de satisfaire ou de d\u00e9passer les normes suivantes <em><strong>les normes ANSI, OSHA, CSA et CE<\/strong><\/em>.<\/p><p>Nous sommes certifi\u00e9s et r\u00e9pondons \u00e0 la norme<em><strong> ISO-17025<\/strong><\/em>De plus, notre processus de production est certifi\u00e9 selon la norme <em><strong>ISO 9001<\/strong> <\/em>et \u00e0 la norme ISO 9001.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b35164f elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"b35164f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"http:\/\/xtirpa.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">en savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-923bc9e e-con-full e-flex e-con e-child\" data-id=\"923bc9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6eea629 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"6eea629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-6.jpg\" class=\"attachment-full size-full wp-image-4473\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-6.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-6-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-6-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-6-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-6-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-6-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-6-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a7522c dce_masking-none elementor-widget elementor-widget-image\" data-id=\"0a7522c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg\" class=\"attachment-full size-full wp-image-4441\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-overlay-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/mesh-gradient-01.webp\" class=\"elementor-element elementor-element-eb63c02 e-con-full e-flex e-con e-parent\" data-id=\"eb63c02\" data-element_type=\"container\" data-e-type=\"container\" id=\"ProductTraceability\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-bac1a2f e-con-full e-flex e-con e-child\" data-id=\"bac1a2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4f5492 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"c4f5492\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-7.jpg\" class=\"attachment-full size-full wp-image-4477\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-7.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-7-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-7-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-7-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-7-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-7-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-7-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c5e49 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"32c5e49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-8.jpg\" class=\"attachment-full size-full wp-image-4478\" alt=\"\" srcset=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-8.jpg 2560w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-8-300x200.jpg 300w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-8-1024x683.jpg 1024w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-8-768x512.jpg 768w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-8-1536x1024.jpg 1536w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-8-2048x1366.jpg 2048w, https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-8-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac51b0b e-con-full e-flex e-con e-child\" data-id=\"ac51b0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f69682 elementor-widget elementor-widget-heading\" data-id=\"8f69682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Tra\u00e7abilit\u00e9 des produits<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bd33b7 elementor-widget elementor-widget-text-editor\" data-id=\"9bd33b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2da4365 elementor-widget elementor-widget-heading\" data-id=\"2da4365\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><h5 class=\"elementor-heading-title elementor-size-default\">La mise en \u0153uvre de mesures rigoureuses de contr\u00f4le de la qualit\u00e9 est essentielle pour fabriquer les produits les plus s\u00fbrs pour notre industrie.<\/h5><\/div><\/div><div class=\"elementor-element elementor-element-d4df97b elementor-widget elementor-widget-spacer\" data-id=\"d4df97b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-spacer\"><div class=\"elementor-spacer-inner\"> <\/div><\/div><\/div><\/div><div class=\"elementor-element elementor-element-8805764 elementor-widget elementor-widget-text-editor\" data-id=\"8805764\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>INNOVA a mis en place un processus de tra\u00e7abilit\u00e9 des produits dans ses op\u00e9rations de production et de commercialisation. <em><strong>ISO-9001<\/strong><\/em>.<\/p><p>Nous sommes en mesure de retracer, gr\u00e2ce aux num\u00e9ros de s\u00e9rie des produits, tous les mat\u00e9riaux critiques provenant de nos fournisseurs.<\/p><p>Nous pouvons identifier les produits sp\u00e9cifiques qui n\u00e9cessitent une attention particuli\u00e8re. Cela permet \u00e0 INNOVA de maintenir son engagement \u00e0 fournir des <strong>produits et des services de haute qualit\u00e9 \u00e0 ses clients<\/strong>. <\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92bff50 elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"92bff50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"http:\/\/xtirpa.com\/company\/partners\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<section data-dce-background-image-url=\"http:\/\/xtirpa.com\/wp-content\/uploads\/2025\/10\/download-3.jpg\" class=\"elementor-element elementor-element-b4a718c e-flex e-con-boxed e-con e-parent\" data-id=\"b4a718c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_range&quot;:&quot;viewport&quot;,&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-dce-background-color=\"#000000\" class=\"elementor-element elementor-element-6e3e7c5 e-con-full e-flex e-con e-child\" data-id=\"6e3e7c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3caae5 elementor-widget elementor-widget-heading\" data-id=\"f3caae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre engagement en mati\u00e8re de s\u00e9curit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e88ee0e elementor-widget elementor-widget-text-editor\" data-id=\"e88ee0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Innova offre \u00e0 l&rsquo;industrie de la s\u00e9curit\u00e9 les syst\u00e8mes les plus innovants et de la plus haute qualit\u00e9 sur le march\u00e9.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0be8ca6 elementor-widget elementor-widget-text-editor\" data-id=\"0be8ca6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Innova, avec sa gamme d&rsquo;\u00e9quipements de protection contre les chutes et de sauvetage\/r\u00e9cup\u00e9ration en espace confin\u00e9 XTIRPA\u2122, r\u00e9pond aux exigences les plus strictes en mati\u00e8re de protection contre les chutes dans le monde.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5712cc9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5712cc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">d\u00e9couvrez nos partenaires<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home UNE GAMME COMPL\u00c8TE DE SERVICES Notre \u00e9quipe d&rsquo;experts a acquis une expertise internationale dans le d\u00e9veloppement de solutions pour les espaces confin\u00e9s. Conseil Installation Solutions Costum Formation Laboratoire d&rsquo;essai Tra\u00e7abilit\u00e9 des produits 1. Consultation Au fil des ans, INNOVA a acquis une expertise internationale dans le d\u00e9veloppement de solutions pour les espaces confin\u00e9s, avec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5701","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Services - Services<\/title>\n<meta name=\"description\" content=\"Searching for confined space safety solutions - Contact us!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xtirpa.moodd.online\/fr\/services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Services - Services\" \/>\n<meta property=\"og:description\" content=\"Searching for confined space safety solutions - Contact us!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xtirpa.moodd.online\/fr\/services\/\" \/>\n<meta property=\"og:site_name\" content=\"Xtirpa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Xtirpa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-20T17:55:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/services\\\/\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/services\\\/\",\"name\":\"Services - Services\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/services\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/services\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/download-4.jpg\",\"datePublished\":\"2025-10-26T18:57:01+00:00\",\"dateModified\":\"2025-12-20T17:55:34+00:00\",\"description\":\"Searching for confined space safety solutions - Contact us!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/services\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/services\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/services\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/download-4.jpg\",\"contentUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/download-4.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/services\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xtirpa.moodd.online\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#website\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/\",\"name\":\"Xtirpa\u2122 - Confined Space and work at height Safety Solutions\",\"description\":\"Engineered safety for access and rescue\",\"publisher\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#organization\"},\"alternateName\":\"Xtirpa\u2122 safety for access and rescue at height and confined space\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xtirpa.moodd.online\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#organization\",\"name\":\"Xtirpa\u2122 - PSP Innova Inc.\",\"alternateName\":\"PSP Innova Inc. - Xtirpa\u2122\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/XTIRPA_yellow.png\",\"contentUrl\":\"https:\\\/\\\/xtirpa.moodd.online\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/XTIRPA_yellow.png\",\"width\":1571,\"height\":544,\"caption\":\"Xtirpa\u2122 - PSP Innova Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/xtirpa.moodd.online\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Xtirpa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/psp-innova\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@xtirpa\",\"https:\\\/\\\/www.instagram.com\\\/xtirpa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Services - Services","description":"Searching for confined space safety solutions - Contact us!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xtirpa.moodd.online\/fr\/services\/","og_locale":"fr_FR","og_type":"article","og_title":"Services - Services","og_description":"Searching for confined space safety solutions - Contact us!","og_url":"https:\/\/xtirpa.moodd.online\/fr\/services\/","og_site_name":"Xtirpa","article_publisher":"https:\/\/www.facebook.com\/Xtirpa\/","article_modified_time":"2025-12-20T17:55:34+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xtirpa.moodd.online\/fr\/services\/","url":"https:\/\/xtirpa.moodd.online\/fr\/services\/","name":"Services - Services","isPartOf":{"@id":"https:\/\/xtirpa.moodd.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xtirpa.moodd.online\/fr\/services\/#primaryimage"},"image":{"@id":"https:\/\/xtirpa.moodd.online\/fr\/services\/#primaryimage"},"thumbnailUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg","datePublished":"2025-10-26T18:57:01+00:00","dateModified":"2025-12-20T17:55:34+00:00","description":"Searching for confined space safety solutions - Contact us!","breadcrumb":{"@id":"https:\/\/xtirpa.moodd.online\/fr\/services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xtirpa.moodd.online\/fr\/services\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/xtirpa.moodd.online\/fr\/services\/#primaryimage","url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg","contentUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/10\/download-4.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/xtirpa.moodd.online\/fr\/services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xtirpa.moodd.online\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Services"}]},{"@type":"WebSite","@id":"https:\/\/xtirpa.moodd.online\/#website","url":"https:\/\/xtirpa.moodd.online\/","name":"Xtirpa\u2122 - Confined Space and work at height Safety Solutions","description":"Engineered safety for access and rescue","publisher":{"@id":"https:\/\/xtirpa.moodd.online\/#organization"},"alternateName":"Xtirpa\u2122 safety for access and rescue at height and confined space","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xtirpa.moodd.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/xtirpa.moodd.online\/#organization","name":"Xtirpa\u2122 - PSP Innova Inc.","alternateName":"PSP Innova Inc. - Xtirpa\u2122","url":"https:\/\/xtirpa.moodd.online\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/xtirpa.moodd.online\/#\/schema\/logo\/image\/","url":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/03\/XTIRPA_yellow.png","contentUrl":"https:\/\/xtirpa.moodd.online\/wp-content\/uploads\/2025\/03\/XTIRPA_yellow.png","width":1571,"height":544,"caption":"Xtirpa\u2122 - PSP Innova Inc."},"image":{"@id":"https:\/\/xtirpa.moodd.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Xtirpa\/","https:\/\/www.linkedin.com\/company\/psp-innova\/","https:\/\/www.youtube.com\/@xtirpa","https:\/\/www.instagram.com\/xtirpa\/"]}]}},"_links":{"self":[{"href":"https:\/\/xtirpa.moodd.online\/fr\/wp-json\/wp\/v2\/pages\/5701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xtirpa.moodd.online\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xtirpa.moodd.online\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xtirpa.moodd.online\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xtirpa.moodd.online\/fr\/wp-json\/wp\/v2\/comments?post=5701"}],"version-history":[{"count":2,"href":"https:\/\/xtirpa.moodd.online\/fr\/wp-json\/wp\/v2\/pages\/5701\/revisions"}],"predecessor-version":[{"id":8929,"href":"https:\/\/xtirpa.moodd.online\/fr\/wp-json\/wp\/v2\/pages\/5701\/revisions\/8929"}],"wp:attachment":[{"href":"https:\/\/xtirpa.moodd.online\/fr\/wp-json\/wp\/v2\/media?parent=5701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}